{"id":45570,"date":"2026-01-07T17:38:58","date_gmt":"2026-01-07T22:38:58","guid":{"rendered":"https:\/\/ambientestereo.fm\/sitio\/?p=45570"},"modified":"2026-01-07T17:39:30","modified_gmt":"2026-01-07T22:39:30","slug":"pdvsa-confirmo-que-vendera-petroleo-a-ee-uu","status":"publish","type":"post","link":"https:\/\/ambientestereo.fm\/sitio\/noticias\/pdvsa-confirmo-que-vendera-petroleo-a-ee-uu\/","title":{"rendered":"PDVSA s\u00ed vender\u00e1 petr\u00f3leo a EE. UU."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Venezuela inform\u00f3 este 7 de enero que negocia con Estados Unidos la \u00abventa de vol\u00famenes\u00bb de crudo, momentos despu\u00e9s de que el gobierno de Donald Trump dijera que controlar\u00e1 la comercializaci\u00f3n de petr\u00f3leo venezolano \u00abindefinidamente\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abCursa una negociaci\u00f3n con Estados Unidos para la venta de vol\u00famenes de petr\u00f3leo, en el marco de las relaciones comerciales que existen entre ambos pa\u00edses\u00bb, indic\u00f3 en un comunicado la empresa estatal Petr\u00f3leos de Venezuela (Pdvsa).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEste proceso se desarrolla bajo esquemas similares a los vigentes con empresas internacionales\u00bb, apunt\u00f3 la compa\u00f1\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El secretario de Energ\u00eda estadounidense, Chris Wright, dijo m\u00e1s temprano que Washington controlar\u00e1 las ventas de petr\u00f3leo venezolano \u00abindefinidamente\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trump hab\u00eda anunciado la v\u00edspera que el gobierno interino Delcy Rodr\u00edguez entregar\u00e1 hasta 50 millones de barriles de petr\u00f3leo a Estados Unidos. Los ingresos ser\u00e1n \u00abcontrolados\u00bb por \u00e9l, precis\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">PDVSA tambi\u00e9n ratific\u00f3 su intenci\u00f3n de \u201ccontinuar construyendo alianzas que impulsen el desarrollo nacional a favor del pueblo venezolano y que contribuyan a la estabilidad energ\u00e9tica global\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La secretaria de prensa de la Casa Blanca, Karoline Leavitt, subray\u00f3 que la entrega de petr\u00f3leo forma parte de un acuerdo bilateral \u201cpara beneficiar a ambos pa\u00edses\u201d. \u201cObviamente, tenemos la m\u00e1xima influencia sobre las autoridades interinas en Venezuela en este momento\u201d, afirm\u00f3 Leavitt, y remarc\u00f3 que, seg\u00fan el presidente Trump, Venezuela dejar\u00e1 de ser un pa\u00eds que \u201cenv\u00eda drogas ilegales a los Estados Unidos de Am\u00e9rica\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuentes: BLU RADIO &#8211; La FM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venezuela inform\u00f3 este 7 de enero que negocia con Estados Unidos la \u00abventa de vol\u00famenes\u00bb&#8230;<\/p>\n","protected":false},"author":6,"featured_media":26054,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[412,287],"tags":[],"class_list":["post-45570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacado","category-noticias"],"acf":[],"comment_count":0,"featured_image_url":"https:\/\/ambientestereo.fm\/sitio\/wp-content\/uploads\/2022\/10\/petroleo.jpg","thumbnail":"https:\/\/ambientestereo.fm\/sitio\/wp-content\/uploads\/2022\/10\/petroleo-150x150.jpg","_links":{"self":[{"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/posts\/45570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/comments?post=45570"}],"version-history":[{"count":2,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/posts\/45570\/revisions"}],"predecessor-version":[{"id":45572,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/posts\/45570\/revisions\/45572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/media\/26054"}],"wp:attachment":[{"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/media?parent=45570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/categories?post=45570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/tags?post=45570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}