{"id":45917,"date":"2026-01-28T00:51:00","date_gmt":"2026-01-28T05:51:00","guid":{"rendered":"https:\/\/ambientestereo.fm\/sitio\/?p=45917"},"modified":"2026-01-27T20:53:36","modified_gmt":"2026-01-28T01:53:36","slug":"trump-cuba-esta-a-punto-de-caer","status":"publish","type":"post","link":"https:\/\/ambientestereo.fm\/sitio\/noticias\/trump-cuba-esta-a-punto-de-caer\/","title":{"rendered":"Trump: Cuba est\u00e1 a punto de caer"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente de Estados Unidos, Donald Trump, asegur\u00f3 que Cuba \u00abest\u00e1 a punto de caer\u00bb porque no recibe petr\u00f3leo de Venezuela desde que Nicol\u00e1s Maduro fue depuesto del poder el pasado 3 de enero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abCuba est\u00e1 a punto de caer. Cuba es una naci\u00f3n que est\u00e1 muy cerca del colapso\u00bb, asegur\u00f3 a la prensa antes de celebrar un mitin en Iowa. El republicano subray\u00f3 que La Habana \u00abobten\u00eda su dinero de Venezuela, obten\u00eda el petr\u00f3leo de Venezuela, pero ya no lo tienen\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre Venezuela, Trump dijo que Estados Unidos tiene \u00abuna presencia muy fuerte\u00bb en ese pa\u00eds que, dijo, tiene \u00ablas mayores reservas de petr\u00f3leo del mundo\u00bb, y afirm\u00f3 que est\u00e1 \u00abtrabajando de manera excelente\u00bb con el gobierno interino de Delcy Rodr\u00edguez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abAhora les ir\u00e1 mejor que nunca y vamos a estar ganando mucho dinero para ellos y mucho dinero para nuestro pa\u00eds. Tenemos una muy buena relaci\u00f3n con los l\u00edderes de Venezuela y vamos a mantenerla as\u00ed\u00bb, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trump sostiene que el gobierno cubano tiene los d\u00edas contados desde el ataque de Estados Unidos a Venezuela del pasado 3 de noviembre que se sald\u00f3 con la captura de Maduro y de su esposa, Cilia Flores, quienes fueron trasladados a Nueva York, donde enfrentan cargos por narcotr\u00e1fico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Washington considera que el fin del env\u00edo de crudo venezolano a la isla provocar\u00e1 un cambio de r\u00e9gimen en Cuba, pa\u00eds afectado por una grave crisis econ\u00f3mica y social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobierno cubano ha condenado como un \u00abacto de terrorismo\u00bb la intervenci\u00f3n en Caracas y advierte que no tolerar\u00e1 la intimidaci\u00f3n ni las amenazas de Estados Unidos, que no descarta incluso el uso de la fuerza militar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: DW<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Estados Unidos, Donald Trump, asegur\u00f3 que Cuba \u00abest\u00e1 a punto de caer\u00bb&#8230;<\/p>\n","protected":false},"author":6,"featured_media":41748,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[287,413],"tags":[],"class_list":["post-45917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-tendencia"],"acf":[],"comment_count":0,"featured_image_url":"https:\/\/ambientestereo.fm\/sitio\/wp-content\/uploads\/2025\/06\/Donald_Trump_2-1.jpg","thumbnail":"https:\/\/ambientestereo.fm\/sitio\/wp-content\/uploads\/2025\/06\/Donald_Trump_2-1-150x150.jpg","_links":{"self":[{"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/posts\/45917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/comments?post=45917"}],"version-history":[{"count":1,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/posts\/45917\/revisions"}],"predecessor-version":[{"id":45918,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/posts\/45917\/revisions\/45918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/media\/41748"}],"wp:attachment":[{"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/media?parent=45917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/categories?post=45917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/tags?post=45917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}