{"id":45963,"date":"2026-02-01T07:10:00","date_gmt":"2026-02-01T12:10:00","guid":{"rendered":"https:\/\/ambientestereo.fm\/sitio\/?p=45963"},"modified":"2026-01-30T21:14:27","modified_gmt":"2026-01-31T02:14:27","slug":"luis-fabian-lanza-mientras-vienes","status":"publish","type":"post","link":"https:\/\/ambientestereo.fm\/sitio\/noticias\/luis-fabian-lanza-mientras-vienes\/","title":{"rendered":"Luis Fabi\u00e1n\u00a0lanza\u00a0\u00abMientras vienes\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El cantautor barranquillero Luis Fabi\u00e1n present\u00f3 en 2025 su primer \u00e1lbum titulado \u00abMientras vienes\u00bb, un proyecto que marca un momento clave en su camino art\u00edstico y espiritual. Como carta de presentaci\u00f3n del \u00e1lbum, se lanz\u00f3 el sencillo \u201c1a de Corintios 13\u201d, una canci\u00f3n que condensa el mensaje y la esencia de toda la producci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Ahora, se da conocer la canci\u00f3n que da t\u00edtulo al \u00e1lbum, una de las m\u00e1s representativas para el int\u00e9rprete. De acuerdo con el propio Luis Fabi\u00e1n, esta composici\u00f3n es una de sus favoritas, ya que \u2014en sus palabras\u2014 es \u201cuna invitaci\u00f3n a vivir con alta expectativa, disfrutar nuestro prop\u00f3sito y regalo de vida en la tierra mientras Cristo regresa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>El \u00e1lbum \u00abMientras vienes\u00bb se construye desde una mirada profundamente personal del artista sobre su caminar de fe. Al referirse al proceso creativo, Luis Fabi\u00e1n se\u00f1ala: \u00abIncursionamos en distintos g\u00e9neros musicales, aunque seguimos con la l\u00ednea de composici\u00f3n po\u00e9tica y aterrizada con la Palabra de Dios\u00bb.<br>A lo largo de cada una de las canciones, el cantautor transmite un mensaje de confianza, dependencia y esperanza en la bondad divina, nutrido tanto por la Palabra de Dios como por experiencias personales que han marcado su vida. En ese mismo sentido, afirma: \u00abEste \u00e1lbum naci\u00f3 del deseo de recordarnos que no estamos aqu\u00ed solo para esperar, sino para mostrar su luz, amar y servir\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En esta nueva etapa de su ministerio, Luis Fabi\u00e1n impulsa un movimiento musical que busca bendecir comunidades en toda Colombia, llevando un mensaje de amor y compromiso con Dios a cada rinc\u00f3n del pa\u00eds, con una proyecci\u00f3n que trasciende fronteras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cantautor barranquillero Luis Fabi\u00e1n present\u00f3 en 2025 su primer \u00e1lbum titulado \u00abMientras vienes\u00bb, un&#8230;<\/p>\n","protected":false},"author":6,"featured_media":45964,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[287,292],"tags":[],"class_list":["post-45963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-mundogospel"],"acf":[],"comment_count":0,"featured_image_url":"https:\/\/ambientestereo.fm\/sitio\/wp-content\/uploads\/2026\/01\/Luis_Fabian.jpg","thumbnail":"https:\/\/ambientestereo.fm\/sitio\/wp-content\/uploads\/2026\/01\/Luis_Fabian-150x150.jpg","_links":{"self":[{"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/posts\/45963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/comments?post=45963"}],"version-history":[{"count":1,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/posts\/45963\/revisions"}],"predecessor-version":[{"id":45965,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/posts\/45963\/revisions\/45965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/media\/45964"}],"wp:attachment":[{"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/media?parent=45963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/categories?post=45963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambientestereo.fm\/sitio\/wp-json\/wp\/v2\/tags?post=45963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}